{"id":8,"count":1,"description":"","link":"https:\/\/blog.fless.me\/index.php\/tag\/unternehmen\/","name":"Unternehmen","slug":"unternehmen","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Unternehmen Archive - Hey, Zukunft!<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.fless.me\/index.php\/tag\/unternehmen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Unternehmen Archive - Hey, Zukunft!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.fless.me\/index.php\/tag\/unternehmen\/\" \/>\n<meta property=\"og:site_name\" content=\"Hey, Zukunft!\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@LadeShootH\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/blog.fless.me\/index.php\/tag\/unternehmen\/\",\"url\":\"https:\/\/blog.fless.me\/index.php\/tag\/unternehmen\/\",\"name\":\"Unternehmen Archive - Hey, Zukunft!\",\"isPartOf\":{\"@id\":\"https:\/\/blog.fless.me\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/blog.fless.me\/index.php\/tag\/unternehmen\/#breadcrumb\"},\"inLanguage\":\"de-DE\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/blog.fless.me\/index.php\/tag\/unternehmen\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/blog.fless.me\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Unternehmen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/blog.fless.me\/#website\",\"url\":\"https:\/\/blog.fless.me\/\",\"name\":\"Hey, Zukunft!\",\"description\":\"Alles \u00fcber Innovationen, Start-Ups und unserer Zukunft.\",\"publisher\":{\"@id\":\"https:\/\/blog.fless.me\/#\/schema\/person\/7c9c4f91e71ef8478e67dea9bd28f8dd\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/blog.fless.me\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de-DE\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\/\/blog.fless.me\/#\/schema\/person\/7c9c4f91e71ef8478e67dea9bd28f8dd\",\"name\":\"Leon Fle\u00df\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/blog.fless.me\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cf85d0e5c560d80a6582120f12cb01c0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cf85d0e5c560d80a6582120f12cb01c0?s=96&d=mm&r=g\",\"caption\":\"Leon Fle\u00df\"},\"logo\":{\"@id\":\"https:\/\/blog.fless.me\/#\/schema\/person\/image\/\"},\"sameAs\":[\"https:\/\/fless.me\",\"Https:\/\/instagram.com\/ladeshooth\",\"https:\/\/www.linkedin.com\/in\/leon-fless\",\"https:\/\/x.com\/LadeShootH\",\"Https:\/\/youtube.com\/ladeshooth\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Unternehmen Archive - Hey, Zukunft!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.fless.me\/index.php\/tag\/unternehmen\/","og_locale":"de_DE","og_type":"article","og_title":"Unternehmen Archive - Hey, Zukunft!","og_url":"https:\/\/blog.fless.me\/index.php\/tag\/unternehmen\/","og_site_name":"Hey, Zukunft!","twitter_card":"summary_large_image","twitter_site":"@LadeShootH","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/blog.fless.me\/index.php\/tag\/unternehmen\/","url":"https:\/\/blog.fless.me\/index.php\/tag\/unternehmen\/","name":"Unternehmen Archive - Hey, Zukunft!","isPartOf":{"@id":"https:\/\/blog.fless.me\/#website"},"breadcrumb":{"@id":"https:\/\/blog.fless.me\/index.php\/tag\/unternehmen\/#breadcrumb"},"inLanguage":"de-DE"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.fless.me\/index.php\/tag\/unternehmen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/blog.fless.me\/"},{"@type":"ListItem","position":2,"name":"Unternehmen"}]},{"@type":"WebSite","@id":"https:\/\/blog.fless.me\/#website","url":"https:\/\/blog.fless.me\/","name":"Hey, Zukunft!","description":"Alles \u00fcber Innovationen, Start-Ups und unserer Zukunft.","publisher":{"@id":"https:\/\/blog.fless.me\/#\/schema\/person\/7c9c4f91e71ef8478e67dea9bd28f8dd"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.fless.me\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de-DE"},{"@type":["Person","Organization"],"@id":"https:\/\/blog.fless.me\/#\/schema\/person\/7c9c4f91e71ef8478e67dea9bd28f8dd","name":"Leon Fle\u00df","image":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/blog.fless.me\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cf85d0e5c560d80a6582120f12cb01c0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cf85d0e5c560d80a6582120f12cb01c0?s=96&d=mm&r=g","caption":"Leon Fle\u00df"},"logo":{"@id":"https:\/\/blog.fless.me\/#\/schema\/person\/image\/"},"sameAs":["https:\/\/fless.me","Https:\/\/instagram.com\/ladeshooth","https:\/\/www.linkedin.com\/in\/leon-fless","https:\/\/x.com\/LadeShootH","Https:\/\/youtube.com\/ladeshooth"]}]}},"_links":{"self":[{"href":"https:\/\/blog.fless.me\/index.php\/wp-json\/wp\/v2\/tags\/8"}],"collection":[{"href":"https:\/\/blog.fless.me\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blog.fless.me\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blog.fless.me\/index.php\/wp-json\/wp\/v2\/posts?tags=8"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}